{"id":1534,"date":"2025-11-01T20:38:59","date_gmt":"2025-11-01T19:38:59","guid":{"rendered":"https:\/\/lunedesfleurs.fr\/?post_type=product&#038;p=1534"},"modified":"2025-12-18T14:24:44","modified_gmt":"2025-12-18T13:24:44","slug":"vulve-fleurie","status":"publish","type":"product","link":"https:\/\/lunedesfleurs.fr\/index.php\/produit\/vulve-fleurie\/","title":{"rendered":"Vulve Fleurie"},"content":{"rendered":"<p>Tableau r\u00e9alis\u00e9 \u00e0 l&rsquo;aquarelle et fleurs s\u00e9ch\u00e9es press\u00e9es artisanalement.<\/p>\n<p>Motif : Vulve<\/p>\n<p>Couleur : Rouge, orange, jaune, rose, color\u00e9<\/p>\n<p>Pi\u00e8ce unique.<\/p>\n<p>Id\u00e9al d\u00e9coration int\u00e9rieur, bureau.<\/p>\n<p>Cadeau original, f\u00eate des m\u00e8res, anniversaire, no\u00ebl.<\/p>\n<p>&nbsp;<\/p>\n<p>Personnalisable sur commande avec Pr\u00e9nom, Date, etc &#8230;<\/p>\n<p>par mail : atelier@lunedesfleurs.fr<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tableau r\u00e9alis\u00e9 \u00e0 l&rsquo;aquarelle et fleurs s\u00e9ch\u00e9es press\u00e9es artisanalement.<\/p>\n<p>Motif : Vulve<\/p>\n<p>Couleur : Rouge, orange, jaune, rose, color\u00e9<\/p>\n<p>12 x 17 cm<\/p>\n","protected":false},"featured_media":1612,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[27,26],"product_tag":[],"class_list":["post-1534","product","type-product","status-publish","has-post-thumbnail","product_cat-femininsacre","product_cat-tableau-herbiers","first","outofstock","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vulve Fleurie - Lune des Fleurs<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lunedesfleurs.fr\/index.php\/produit\/vulve-fleurie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vulve Fleurie - Lune des Fleurs\" \/>\n<meta property=\"og:description\" content=\"Tableau r\u00e9alis\u00e9 \u00e0 l&#039;aquarelle et fleurs s\u00e9ch\u00e9es press\u00e9es artisanalement.  Motif : Vulve  Couleur : Rouge, orange, jaune, rose, color\u00e9  12 x 17 cm\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lunedesfleurs.fr\/index.php\/produit\/vulve-fleurie\/\" \/>\n<meta property=\"og:site_name\" content=\"Lune des Fleurs\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lunedesfleurs.fr\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-18T13:24:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lunedesfleurs.fr\/wp-content\/uploads\/2025\/10\/vulve-2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lunedesfleurs.fr\/index.php\/produit\/vulve-fleurie\/\",\"url\":\"https:\/\/lunedesfleurs.fr\/index.php\/produit\/vulve-fleurie\/\",\"name\":\"Vulve Fleurie - Lune des Fleurs\",\"isPartOf\":{\"@id\":\"https:\/\/lunedesfleurs.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/lunedesfleurs.fr\/index.php\/produit\/vulve-fleurie\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/lunedesfleurs.fr\/index.php\/produit\/vulve-fleurie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/lunedesfleurs.fr\/wp-content\/uploads\/2025\/10\/vulve-2-scaled.jpg\",\"datePublished\":\"2025-11-01T19:38:59+00:00\",\"dateModified\":\"2025-12-18T13:24:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/lunedesfleurs.fr\/index.php\/produit\/vulve-fleurie\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lunedesfleurs.fr\/index.php\/produit\/vulve-fleurie\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/lunedesfleurs.fr\/index.php\/produit\/vulve-fleurie\/#primaryimage\",\"url\":\"https:\/\/lunedesfleurs.fr\/wp-content\/uploads\/2025\/10\/vulve-2-scaled.jpg\",\"contentUrl\":\"https:\/\/lunedesfleurs.fr\/wp-content\/uploads\/2025\/10\/vulve-2-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Tableau herbier fleurs s\u00e9ch\u00e9es pouvoir f\u00e9minin sacr\u00e9 fait main\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lunedesfleurs.fr\/index.php\/produit\/vulve-fleurie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/lunedesfleurs.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\/\/lunedesfleurs.fr\/index.php\/boutique\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vulve Fleurie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lunedesfleurs.fr\/#website\",\"url\":\"https:\/\/lunedesfleurs.fr\/\",\"name\":\"Lune des Fleurs\",\"description\":\"Cr\u00e9ations fran\u00e7aises - Fait main avec C\u0153ur, Intention et un soup\u00e7on de Magie\",\"publisher\":{\"@id\":\"https:\/\/lunedesfleurs.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lunedesfleurs.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/lunedesfleurs.fr\/#organization\",\"name\":\"Lune des Fleurs\",\"url\":\"https:\/\/lunedesfleurs.fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/lunedesfleurs.fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/lunedesfleurs.fr\/wp-content\/uploads\/2025\/11\/LDF_LOGO_HORIZ_RVB_BN_F_TRANS-scaled.png\",\"contentUrl\":\"https:\/\/lunedesfleurs.fr\/wp-content\/uploads\/2025\/11\/LDF_LOGO_HORIZ_RVB_BN_F_TRANS-scaled.png\",\"width\":2560,\"height\":1281,\"caption\":\"Lune des Fleurs\"},\"image\":{\"@id\":\"https:\/\/lunedesfleurs.fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/lunedesfleurs.fr\",\"https:\/\/www.instagram.com\/lunedesfleurs.fr\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vulve Fleurie - Lune des Fleurs","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lunedesfleurs.fr\/index.php\/produit\/vulve-fleurie\/","og_locale":"fr_FR","og_type":"article","og_title":"Vulve Fleurie - Lune des Fleurs","og_description":"Tableau r\u00e9alis\u00e9 \u00e0 l'aquarelle et fleurs s\u00e9ch\u00e9es press\u00e9es artisanalement.  Motif : Vulve  Couleur : Rouge, orange, jaune, rose, color\u00e9  12 x 17 cm","og_url":"https:\/\/lunedesfleurs.fr\/index.php\/produit\/vulve-fleurie\/","og_site_name":"Lune des Fleurs","article_publisher":"https:\/\/www.facebook.com\/lunedesfleurs.fr","article_modified_time":"2025-12-18T13:24:44+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/lunedesfleurs.fr\/wp-content\/uploads\/2025\/10\/vulve-2-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lunedesfleurs.fr\/index.php\/produit\/vulve-fleurie\/","url":"https:\/\/lunedesfleurs.fr\/index.php\/produit\/vulve-fleurie\/","name":"Vulve Fleurie - Lune des Fleurs","isPartOf":{"@id":"https:\/\/lunedesfleurs.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lunedesfleurs.fr\/index.php\/produit\/vulve-fleurie\/#primaryimage"},"image":{"@id":"https:\/\/lunedesfleurs.fr\/index.php\/produit\/vulve-fleurie\/#primaryimage"},"thumbnailUrl":"https:\/\/lunedesfleurs.fr\/wp-content\/uploads\/2025\/10\/vulve-2-scaled.jpg","datePublished":"2025-11-01T19:38:59+00:00","dateModified":"2025-12-18T13:24:44+00:00","breadcrumb":{"@id":"https:\/\/lunedesfleurs.fr\/index.php\/produit\/vulve-fleurie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lunedesfleurs.fr\/index.php\/produit\/vulve-fleurie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lunedesfleurs.fr\/index.php\/produit\/vulve-fleurie\/#primaryimage","url":"https:\/\/lunedesfleurs.fr\/wp-content\/uploads\/2025\/10\/vulve-2-scaled.jpg","contentUrl":"https:\/\/lunedesfleurs.fr\/wp-content\/uploads\/2025\/10\/vulve-2-scaled.jpg","width":2560,"height":1707,"caption":"Tableau herbier fleurs s\u00e9ch\u00e9es pouvoir f\u00e9minin sacr\u00e9 fait main"},{"@type":"BreadcrumbList","@id":"https:\/\/lunedesfleurs.fr\/index.php\/produit\/vulve-fleurie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lunedesfleurs.fr\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/lunedesfleurs.fr\/index.php\/boutique\/"},{"@type":"ListItem","position":3,"name":"Vulve Fleurie"}]},{"@type":"WebSite","@id":"https:\/\/lunedesfleurs.fr\/#website","url":"https:\/\/lunedesfleurs.fr\/","name":"Lune des Fleurs","description":"Cr\u00e9ations fran\u00e7aises - Fait main avec C\u0153ur, Intention et un soup\u00e7on de Magie","publisher":{"@id":"https:\/\/lunedesfleurs.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lunedesfleurs.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lunedesfleurs.fr\/#organization","name":"Lune des Fleurs","url":"https:\/\/lunedesfleurs.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lunedesfleurs.fr\/#\/schema\/logo\/image\/","url":"https:\/\/lunedesfleurs.fr\/wp-content\/uploads\/2025\/11\/LDF_LOGO_HORIZ_RVB_BN_F_TRANS-scaled.png","contentUrl":"https:\/\/lunedesfleurs.fr\/wp-content\/uploads\/2025\/11\/LDF_LOGO_HORIZ_RVB_BN_F_TRANS-scaled.png","width":2560,"height":1281,"caption":"Lune des Fleurs"},"image":{"@id":"https:\/\/lunedesfleurs.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lunedesfleurs.fr","https:\/\/www.instagram.com\/lunedesfleurs.fr\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lunedesfleurs.fr\/index.php\/wp-json\/wp\/v2\/product\/1534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lunedesfleurs.fr\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lunedesfleurs.fr\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lunedesfleurs.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1534"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lunedesfleurs.fr\/index.php\/wp-json\/wp\/v2\/media\/1612"}],"wp:attachment":[{"href":"https:\/\/lunedesfleurs.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1534"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lunedesfleurs.fr\/index.php\/wp-json\/wp\/v2\/product_brand?post=1534"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lunedesfleurs.fr\/index.php\/wp-json\/wp\/v2\/product_cat?post=1534"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lunedesfleurs.fr\/index.php\/wp-json\/wp\/v2\/product_tag?post=1534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}